{"id":2237,"count":1,"description":"","link":"https:\/\/www.brh.org.uk\/site\/tag\/english-revolution\/","name":"English Revolution","slug":"english-revolution","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>English Revolution Archives - Bristol Radical History Group<\/title>\n<meta name=\"description\" content=\"English Revolution related articles, events, pamphlets and books.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.brh.org.uk\/site\/tag\/english-revolution\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"English Revolution Archives - Bristol Radical History Group\" \/>\n<meta property=\"og:description\" content=\"English Revolution related articles, events, pamphlets and books.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.brh.org.uk\/site\/tag\/english-revolution\/\" \/>\n<meta property=\"og:site_name\" content=\"Bristol Radical History Group\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.brh.org.uk\/site\/wp-content\/uploads\/2014\/02\/logo_red_background.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"English Revolution Archives - Bristol Radical History Group","description":"English Revolution related articles, events, pamphlets and books.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.brh.org.uk\/site\/tag\/english-revolution\/","og_locale":"en_US","og_type":"article","og_title":"English Revolution Archives - Bristol Radical History Group","og_description":"English Revolution related articles, events, pamphlets and books.","og_url":"https:\/\/www.brh.org.uk\/site\/tag\/english-revolution\/","og_site_name":"Bristol Radical History Group","og_image":[{"width":500,"height":500,"url":"https:\/\/www.brh.org.uk\/site\/wp-content\/uploads\/2014\/02\/logo_red_background.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.brh.org.uk\/site\/tag\/english-revolution\/","url":"https:\/\/www.brh.org.uk\/site\/tag\/english-revolution\/","name":"English Revolution Archives - Bristol Radical History Group","isPartOf":{"@id":"https:\/\/www.brh.org.uk\/site\/#website"},"description":"English Revolution related articles, events, pamphlets and books.","inLanguage":"en-US"},{"@type":"WebSite","@id":"https:\/\/www.brh.org.uk\/site\/#website","url":"https:\/\/www.brh.org.uk\/site\/","name":"Bristol Radical History Group","description":"History From Below","publisher":{"@id":"https:\/\/www.brh.org.uk\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.brh.org.uk\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.brh.org.uk\/site\/#organization","name":"Bristol Radical History Group","alternateName":"BRHG","url":"https:\/\/www.brh.org.uk\/site\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.brh.org.uk\/site\/#\/schema\/logo\/image\/","url":"https:\/\/www.brh.org.uk\/site\/wp-content\/uploads\/2020\/07\/full-logo-small.png","contentUrl":"https:\/\/www.brh.org.uk\/site\/wp-content\/uploads\/2020\/07\/full-logo-small.png","width":594,"height":500,"caption":"Bristol Radical History Group"},"image":{"@id":"https:\/\/www.brh.org.uk\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/126960655805\/","https:\/\/bsky.app\/profile\/brisradhis.bsky.social"]}]}},"_links":{"self":[{"href":"https:\/\/www.brh.org.uk\/site\/wp-json\/wp\/v2\/tags\/2237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brh.org.uk\/site\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.brh.org.uk\/site\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.brh.org.uk\/site\/wp-json\/wp\/v2\/posts?tags=2237"},{"href":"https:\/\/www.brh.org.uk\/site\/wp-json\/wp\/v2\/events?tags=2237"},{"href":"https:\/\/www.brh.org.uk\/site\/wp-json\/wp\/v2\/pamphlets?tags=2237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}